{"id":1579,"date":"2022-05-09T15:32:31","date_gmt":"2022-05-09T13:32:31","guid":{"rendered":"https:\/\/www.osellameavvocati.it\/web\/?page_id=1579"},"modified":"2022-09-30T09:11:38","modified_gmt":"2022-09-30T07:11:38","slug":"studio","status":"publish","type":"page","link":"https:\/\/www.osellameavvocati.it\/web\/studio\/","title":{"rendered":"Studio"},"content":{"rendered":"\n<div class=\"wp-block-ivory-heading heading\"><header class=\"heading--entry\"><div class=\"row\"><div class=\"col-12 col-lg-10\"><h6 class=\"heading__subtitle mt-0\" style=\"color: #363431;\">Lo Studio<\/h6><h1 class=\"heading__title m-0\" style=\"color: #ba9678;\">Assistenza e consulenza legale<\/h1><\/div><\/div><\/header><\/div>\n\n\n\n<div class=\"wp-block-ivory-image-distortion-effect image-distortion-effect\"><div class=\"image-distortion-effect__display image-distortion-effect__display--center pattern\"><div class=\"poster poster--horizontal\" data-src=\"https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/hader-contatti.jpg\" data-id=\"1693\"><figure><\/figure><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\" style=\"flex-basis:33.33%\">\n<h4 style=\"color:#ba9678\">La nostra strategia \u00e8 cogliere la visione generale del problema per risolverlo<\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column\" style=\"flex-basis:66.66%\">\n<p><\/p>\n\n\n\n<p>Ogni giorno il nostro team lavora a stretto contatto con i clienti, assicurando un supporto nella condivisione dei problemi e nella scelta delle soluzioni al fine di tutelare al meglio sia le singole persone sia le societ\u00e0 che si trovino coinvolte, loro malgrado, come vittime o come imputati in processi penali o in questioni afferenti i diritti fondamentali e le libert\u00e0 personali.<\/p>\n\n\n\n<p>Non ci limitiamo a vincere la causa ma cerchiamo di cogliere la visione generale del problema per risolverlo e gestirlo con la strategia pi\u00f9 efficace per il benessere del cliente.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"556\" src=\"https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/header-contatti-1024x556.jpg\" alt=\"Avvocato Montebelluna Treviso\" class=\"wp-image-1678\" srcset=\"https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/header-contatti-1024x556.jpg 1024w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/header-contatti-300x163.jpg 300w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/header-contatti-768x417.jpg 768w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/header-contatti-1536x834.jpg 1536w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/header-contatti-1014x550.jpg 1014w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/header-contatti.jpg 1920w\" sizes=\"100vw\" \/><\/figure>\n\n\n\n<h5 style=\"color:#ba9678\">ETICA<\/h5>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"556\" src=\"https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/completezza-1024x556.jpg\" alt=\"\" class=\"wp-image-1673\" srcset=\"https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/completezza-1024x556.jpg 1024w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/completezza-300x163.jpg 300w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/completezza-768x417.jpg 768w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/completezza-1536x834.jpg 1536w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/completezza-1014x550.jpg 1014w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/completezza.jpg 1920w\" sizes=\"100vw\" \/><\/figure>\n\n\n\n<h5 style=\"color:#ba9678\">COMPETENZA<\/h5>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"556\" src=\"https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/procedura-penale-1024x556.jpg\" alt=\"\" class=\"wp-image-1773\" srcset=\"https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/procedura-penale-1024x556.jpg 1024w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/procedura-penale-300x163.jpg 300w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/procedura-penale-768x417.jpg 768w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/procedura-penale-1536x834.jpg 1536w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/procedura-penale-1014x550.jpg 1014w, https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/procedura-penale.jpg 1920w\" sizes=\"100vw\" \/><\/figure>\n\n\n\n<h5 style=\"color:#ba9678\"> PROFESSIONALIT\u00c0<\/h5>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 style=\"color:#000\">Lo Studio riserva molta attenzione all\u2019aspetto personale e al rapporto fiduciario cliente\/professionista attraverso chiarezza e riservatezza, che permettono la tutela dei diritti in un clima di profonda e costruttiva fiducia.<\/h5>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ivory-services-expanded services-expanded\"><div class=\"services-expanded__inner\"><div class=\"row\"><div class=\"services-expanded__thumb col-12 col-lg-5\"><div class=\"poster pattern\" data-src=\"https:\/\/www.osellameavvocati.it\/web\/wp-content\/uploads\/2022\/06\/avv-luisa-osellame-treviso.jpg\" data-id=\"1742\"><a href=\"https:\/\/www.osellameavvocati.it\/web\/luisa-osellame\/\"><figure><\/figure><\/a><\/div><\/div><div class=\"services-expanded__content col-12 col-lg-4 offset-lg-1\"><h4 class=\"services-expanded__title\">Luisa Osellame<\/h4><div class=\"services-expanded__copy\"><div class=\"services-expanded__desc mb-3\">Mi sono laureata in Giurisprudenza presso l&#8217;Universit\u00e0 degli Studi di Trento nel 2000, discutendo la tesi in Diritto Penale dell\u2019economia e delle societ\u00e0. Esercito dall\u2019anno 2003 la professione di Avvocato iscritta all&#8217;Ordine del Foro di Treviso; dall\u2019anno 2015 ho conseguito il Patrocinio avanti alle Giurisdizioni Superiori.<\/div><p class=\"services-expanded__cta\"><a class=\"btn pattern\" href=\"https:\/\/www.osellameavvocati.it\/web\/luisa-osellame\/\"><i class=\"icon i-keyboard-arrow-right\" aria-hidden=\"true\"><\/i><span>LEGGI TUTTO<\/span><\/a><\/p><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lo Studio Assistenza e consulenza legale La nostra strategia \u00e8 cogliere la visione generale del problema per risolverlo Ogni giorno il nostro team lavora a&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1693,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/pages\/1579"}],"collection":[{"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/comments?post=1579"}],"version-history":[{"count":29,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/pages\/1579\/revisions"}],"predecessor-version":[{"id":1980,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/pages\/1579\/revisions\/1980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/media\/1693"}],"wp:attachment":[{"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/media?parent=1579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}