{"id":2114,"date":"2024-07-09T10:12:03","date_gmt":"2024-07-09T08:12:03","guid":{"rendered":"https:\/\/www.osellameavvocati.it\/web\/?p=2114"},"modified":"2024-07-09T10:31:09","modified_gmt":"2024-07-09T08:31:09","slug":"il-delitto-di-furto-e-la-procedibilita-a-querela-della-persona-offesa","status":"publish","type":"post","link":"https:\/\/www.osellameavvocati.it\/web\/il-delitto-di-furto-e-la-procedibilita-a-querela-della-persona-offesa\/","title":{"rendered":"Il delitto di furto e la procedibilit\u00e0 a querela della persona offesa\u00a0"},"content":{"rendered":"\n<p>Con l\u2019entrata in vigore della Riforma Cartabia, il sistema giuridico italiano ha subito importanti modifiche, soprattutto riguardo alla procedibilit\u00e0 di molti reati che diventano \u201ca querela\u201d della persona offesa (anzich\u00e9 di ufficio, cio\u00e8 perseguiti senza bisogno di una querela, con l\u2019azione penale avviata direttamente dalle autorit\u00e0 competenti).<\/p>\n\n\n\n<ul><li><strong>Nuove regole sulla procedibilit\u00e0 a querela nel delitto di furto<\/strong><\/li><\/ul>\n\n\n\n<p>Il delitto di furto, disciplinato dagli articoli 624 e seguenti del Codice penale, ha subito un sostanziale cambiamento, passando da una procedibilit\u00e0 d\u2019ufficio a una procedibilit\u00e0 a querela in molti casi, anche nei casi aggravati ex art. 625 Codice penale.<\/p>\n\n\n\n<p>Ora, ad esempio, anche nella forma aggravata dell\u2019esposizione del bene alla pubblica fede, il furto \u00e8 procedibile a querela di parte.<\/p>\n\n\n\n<p>Tuttavia, vi sono dei casi in cui il reato di furto rimane procedibile d\u2019ufficio, come stabilito dall\u2019articolo 624 comma 3 del Codice penale, che recita:&nbsp;<em>\u201cIl delitto \u00e8 punibile a querela della persona offesa. Si procede, tuttavia, d\u2019ufficio se la persona offesa \u00e8 incapace, per et\u00e0 o infermit\u00e0, ovvero se ricorre taluna delle circostanze di cui all\u2019articolo 625, numeri 7, salvo che il fatto sia commesso su cose esposte alla pubblica fede, e 7-bis\u201d.<\/em><\/p>\n\n\n\n<ul><li><strong>Casi di procedibilit\u00e0 d\u2019ufficio<\/strong><\/li><\/ul>\n\n\n\n<p>Il furto \u00e8 procedibile d\u2019ufficio nei seguenti casi:<\/p>\n\n\n\n<ol type=\"1\"><li>quando la persona offesa \u00e8 incapace, per et\u00e0 o infermit\u00e0;<\/li><li>nei casi indicati al numero 7 del primo comma dell\u2019articolo 625 c.p., ovvero se il fatto \u00e8 commesso su cose esistenti in uffici o stabilimenti pubblici, sottoposte a sequestro o pignoramento o destinate a pubblico servizio o a pubblica utilit\u00e0, difesa o reverenza;<\/li><li>nel caso previsto dal numero 7-bis dello stesso articolo, se il fatto \u00e8 commesso su componenti metalliche o altro materiale sottratto a infrastrutture destinate all\u2019erogazione di energia, servizi di trasporto, telecomunicazioni o altri servizi pubblici o privati in regime di concessione pubblica;<\/li><li>e sicuramente nei casi di furto in abitazione e furto con strappo disciplinati dall\u2019art. 624 bis c.p..<\/li><\/ol>\n\n\n\n<ul><li><strong>Pronunce recenti della Corte Suprema di Cassazione sul tema<\/strong><\/li><\/ul>\n\n\n\n<p>La Corte Suprema di Cassazione ha fornito chiarimenti importanti su questi aspetti.&nbsp;<\/p>\n\n\n\n<p>Ad esempio, i giudici di legittimit\u00e0 hanno statuito che il&nbsp;<strong>furto di energia elettrica<\/strong>, aggravato ex art. 625, n. 7 Codice penale, \u00e8 ancora&nbsp;<strong>procedibile d\u2019ufficio&nbsp;<\/strong>poich\u00e9 si tratta di un bene destinato a servizio pubblico.&nbsp;<\/p>\n\n\n\n<p>In particolare, la Corte ha affermato: &#8220;<em>La procedibilit\u00e0 a querela disposta dalla novella legislativa \u00e8 esclusa ove la persona offesa risulti incapace, per et\u00e0 o per infermit\u00e0, oppure qualora ricorra taluna delle circostanze ex art. 625, n. 7, c.p., salvo che il fatto sia commesso su cose esposte alla pubblica fede, nonch\u00e9 7-bis. Ne consegue che, essendo stata la condotta commessa su un bene, come l&#8217;energia elettrica, destinato a servizio pubblico, il reato deve ritenersi tuttora procedibile d&#8217;ufficio<\/em>&#8221; (C., Sez. IV, 8.2-7.3.2023, n. 9452).<\/p>\n\n\n\n<p>Inoltre, riguardo alle aggravanti di cui ai n. 2 (se il colpevole usa violenza sulle cose) e 7, quest\u2019ultima con riferimento al&nbsp;<strong>fatto di aver agito su cosa esposta per necessit\u00e0 e per destinazione alla pubblica fede<\/strong>, la Corte ha ulteriormente precisato: &#8220;<em>Laddove la contestazione formulata nei confronti dell&#8217;imputato contempla le circostanze aggravanti di cui all&#8217;art. 625, comma 1, nn. 2 e 7, cod. pen., (quest&#8217;ultima relativamente al fatto di aver agito su cosa esposta per necessit\u00e0 e per destinazione alla pubblica fede), il D.Lgs. 10 ottobre 2022, n. 150, ha previsto la&nbsp;<strong>procedibilit\u00e0 a querela di parte<\/strong>, limitando la procedibilit\u00e0 d&#8217;ufficio ad alcune, limitate, eccezioni, tra le quali rientra quella, anch&#8217;essa contemplata al predetto n. 7), in cui il fatto sia commesso su cose destinate a pubblico servizio. In difetto della necessaria querela, dunque, l&#8217;azione penale rispetto al reato di furto aggravato non pu\u00f2 essere proseguita per mancanza della condizione di procedibilit\u00e0<\/em>&#8221; (C., Sez. IV, 29.11.2023-1.2.2024, n. 4321).<\/p>\n\n\n\n<ul><li><strong>L&#8217;importanza di sporgere querela e seguire il procedimento penale<\/strong><\/li><\/ul>\n\n\n\n<p>Questa modifica nella procedibilit\u00e0 dei reati ha conseguenze pratiche rilevanti. Da un lato, mira a ridurre il carico di lavoro dei tribunali, promuovendo l\u2019utilizzo di strumenti deflattivi. Dall\u2019altro, emerge la necessit\u00e0 di una&nbsp;<strong>maggiore tutela per le vittime<\/strong>, che devono ora partecipare attivamente al procedimento penale.<\/p>\n\n\n\n<p>In questo contesto, \u00e8 utile rivolgersi a un avvocato esperto per redigere correttamente la querela (con tutte le allegazioni necessarie) e soprattutto per seguire poi gli sviluppi del procedimento penale al fine di ottenere un&nbsp;<strong>risarcimento del danno<\/strong>.&nbsp;<\/p>\n\n\n\n<ul><li><strong>Estinzione dei reati procedibili a querela attraverso condotte riparatorie<\/strong><\/li><\/ul>\n\n\n\n<p>Infatti, essendo ora un aspetto fondamentale dei reati procedibili a querela la possibilit\u00e0 di estinguere il reato tramite condotte riparatorie da parte dell\u2019indagato e\/o imputato, vi \u00e8 un aumento delle richieste di&nbsp;<strong>risoluzione dei conflitti anche in modo extragiudiziale<\/strong>.<\/p>\n\n\n\n<p>Gli indagati\/imputati affinch\u00e9 il procedimento si estingua hanno tutto l\u2019interesse di promuovere attivamente la riparazione del danno e la riconciliazione tra le parti, anche nei casi di furto aggravato.<\/p>\n\n\n\n<ul><li><strong>In conclusione<\/strong><\/li><\/ul>\n\n\n\n<p>Alla luce della riforma, \u00e8 consigliabile rivolgersi ad un professionista qualificato per ottenere una maggiore tutela legale. Salvo i casi particolari sopra menzionati, il reato di furto \u00e8 procedibile a querela di parte. Ci\u00f2 significa che, anche se le autorit\u00e0 (Polizia, Carabinieri ecc.) vengono a conoscenza di un reato, non possono procedere senza la querela della persona offesa.<\/p>\n\n\n\n<p>La querela della persona offesa rappresenta una condizione di procedibilit\u00e0 necessaria con cui <strong>la vittima esprime la volont\u00e0 di perseguire penalmente l\u2019autore del reato<\/strong>. Redigere la querela con l\u2019assistenza di un avvocato \u00e8 opportuno per assicurarsi la completezza e correttezza del documento, garantendo cos\u00ec che il processo penale possa procedere successivamente senza intoppi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con l\u2019entrata in vigore della Riforma Cartabia, il sistema giuridico italiano ha subito importanti modifiche, soprattutto riguardo alla procedibilit\u00e0 di molti reati che diventano \u201ca&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2116,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/posts\/2114"}],"collection":[{"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/comments?post=2114"}],"version-history":[{"count":6,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/posts\/2114\/revisions"}],"predecessor-version":[{"id":2122,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/posts\/2114\/revisions\/2122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/media\/2116"}],"wp:attachment":[{"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/media?parent=2114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/categories?post=2114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.osellameavvocati.it\/web\/wp-json\/wp\/v2\/tags?post=2114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}